{"id":32877,"date":"2024-04-26T16:59:00","date_gmt":"2024-04-26T13:59:00","guid":{"rendered":"https:\/\/boat-demo.axiomprotocol.org\/?post_type=product&#038;p=32877"},"modified":"2024-04-26T17:21:20","modified_gmt":"2024-04-26T14:21:20","slug":"ram-tough-claw-baza-cu-clema-mica-cu-minge","status":"publish","type":"product","link":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/","title":{"rendered":"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"32877\" class=\"elementor elementor-32877 elementor-32876\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2769591c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2769591c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b650852\" data-id=\"b650852\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa881aa elementor-widget elementor-widget-heading\" data-id=\"fa881aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Caracteristici<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4590aae5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4590aae5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a40fcfa\" data-id=\"6a40fcfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18caa7 elementor-widget elementor-widget-text-editor\" data-id=\"18caa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"tt-list01\"><li>Versiunea mic\u0103 este proiectat\u0103 pentru a se fixa rapid pe \u0219ine \u0219i bare rotunde, p\u0103trate \u0219i cu forme neobi\u0219nuite cu un diametru exterior cuprins \u00eentre 0,625&#8243; \u0219i 1,5&#8243;; pad-urile de cauciuc asigur\u0103 prindere stabil\u0103 \u0219i protec\u021bie a suprafe\u021bei de montare<\/li><li>Baz\u0103 ideal\u0103 pentru montarea telefoanelor, tabletelor, camerelor, suporturilor pentru undi\u021be \u0219i multe altele; include o minge de cauciuc de 1&#8243; de dimensiune B pentru ata\u0219area la bra\u021bele duble de dimensiune RAM\u00ae<\/li><li>Fabricat din compozite de \u00eenalt\u0103 rezisten\u021b\u0103 \u0219i componente din o\u021bel inoxidabil pentru durabilitate \u0219i fiabilitate \u00een cele mai solicitante medii<\/li><li>Sprijinit de o garan\u021bie limitat\u0103<\/li><li>Versiunea mic\u0103 este proiectat\u0103 pentru a se fixa rapid pe \u0219ine \u0219i bare rotunde, p\u0103trate \u0219i cu forme neobi\u0219nuite cu un diametru exterior cuprins \u00eentre 0,625&#8243; \u0219i 1,14&#8243;; pad-urile de cauciuc asigur\u0103 prindere stabil\u0103 \u0219i protec\u021bie a suprafe\u021bei de montare<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2175ac89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2175ac89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60203d26\" data-id=\"60203d26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2480a5b9 elementor-widget elementor-widget-heading\" data-id=\"2480a5b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Specifica\u021bii<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77c87d65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77c87d65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-303c5458\" data-id=\"303c5458\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64872eaf elementor-widget elementor-widget-text-editor\" data-id=\"64872eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table style=\"width: 100%\"><tbody><tr><td><strong>GREUTATEA PRODUSULUI<\/strong><\/td><td><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">150 g<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>DIMENSIUNI PRODUS<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Overall Height: 4.24&#8243;<br \/>Overall Width: 1.18&#8243;<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>INTERVAL DE PRINDERE<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">.625&#8243; &#8211; 1.14&#8243; diameter<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>CAPACITATEA DE GREUTATE<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div id=\"container\" class=\"projector_page container max-width-1200\"><div id=\"layout\" class=\"row clearfix\"><div id=\"content\" class=\"col-12\"><div id=\"projector_long-info_container_desktop\"><div id=\"long-desc-param\" class=\"tab-content-info\"><section id=\"projector_dictionary\" class=\"dictionary mt-2\"><div class=\"dictionary__group --first --no-group\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Standard Use: 907.18 gramss<br \/>Heavy-Duty Use: 453.59 grams<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>MATERIALE<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div id=\"container\" class=\"projector_page container max-width-1200\"><div id=\"layout\" class=\"row clearfix\"><div id=\"content\" class=\"col-12\"><div id=\"projector_long-info_container_desktop\"><div id=\"long-desc-param\" class=\"tab-content-info\"><section id=\"projector_dictionary\" class=\"dictionary mt-2\"><div class=\"dictionary__group --first --no-group\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">High strength composite<br \/><\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>TIP AMBALAJ<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Poly Bag<\/span><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>TIP MONTARE<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Handlebar\/Rail<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Flat Edge Clamp<\/span><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>INTERVAL DE DIAMETRU<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">.625&#8243; &#8211; 1.14&#8243;<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>DIMENSIUNEA BILEI \u0218I A PRINDERII<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">B Size 1&#8243; (Holds 907.18 gramss)<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>TIP VEHICUL<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Motorcycle<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">ATV<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">UTV<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Bicycle<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Aircraft<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Dirt Bike<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Kayak<\/span><\/div><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">Power Boat<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><tr><td><strong>DIMENSIUNE BIL\u0102<\/strong><\/td><td><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__value\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><div id=\"container\" class=\"projector_page container max-width-1200\"><div id=\"layout\" class=\"row clearfix\"><div id=\"content\" class=\"col-12\"><div id=\"projector_long-info_container_desktop\"><div id=\"long-desc-param\" class=\"tab-content-info\"><section id=\"projector_dictionary\" class=\"dictionary mt-2\"><div class=\"dictionary__group --first --no-group\"><div class=\"dictionary__param\"><div class=\"dictionary__values\"><div class=\"dictionary__value\"><span class=\"dictionary__value_txt\">B Size (1&#8243;)<\/span><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-wkzok-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-wkzok-1n7m0yu\">\n<div class=\"flex flex-col text-sm pb-9\">\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-141\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 juice:gap-4 juice:md:gap-6 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"c07c9c84-0baa-4c40-a1b5-9ca1dd3180bf\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>RAM Tough-Claw este baza perfect\u0103 pentru montare f\u0103r\u0103 unelte pe \u0219ine \u0219i bare rotunde, p\u0103trate \u0219i cu forme neobi\u0219nuite. Versiunea mic\u0103 a RAM Tough-Claw poate fi fixat\u0103 rapid pe \u0219ine cu diametrul exterior cuprins \u00eentre 0,625&#8243; \u0219i 1,14&#8243; \u0219i este ideal\u0103 pentru montarea telefoanelor, tabletelor, camerelor de ac\u021biune, suporturilor pentru undi\u021be \u0219i multe altele \u00eentr-o varietate larg\u0103 de aplica\u021bii. Potrivit\u0103 pentru montarea pe yoke-ul unei aeronave, pe ghidonul bicicletelor \u0219i motocicletelor, sau chiar pe \u0219inele \u0219i barele de kayak, RAM Tough-Claw va deveni \u00een cur\u00e2nd un alt component esen\u021bial al colec\u021biei dvs. RAM.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":32879,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[343,340],"product_tag":[],"class_list":{"0":"post-32877","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ram-mounts_ro","7":"product_cat-sisteme-de-prindere-ro","8":"tt-post","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge - BoatsExpert<\/title>\n<meta name=\"description\" content=\"Cump\u0103ra\u021bi RAM Tough-Claw Baza cu clema mica cu minge \u00een Rom\u00e2nia de la Boats Expert. \u041e gam\u0103 larg\u0103 de accesorii pentru b\u0103rci cu motor cu livrare \u00een toat\u0103 Rom\u00e2nia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge - BoatsExpert\" \/>\n<meta property=\"og:description\" content=\"Cump\u0103ra\u021bi RAM Tough-Claw Baza cu clema mica cu minge \u00een Rom\u00e2nia de la Boats Expert. \u041e gam\u0103 larg\u0103 de accesorii pentru b\u0103rci cu motor cu livrare \u00een toat\u0103 Rom\u00e2nia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/\" \/>\n<meta property=\"og:site_name\" content=\"BoatsExpert\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T14:21:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boatsexpert.com\/wp-content\/uploads\/2024\/04\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/\",\"url\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/\",\"name\":\"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge - BoatsExpert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boatsexpert.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg\",\"datePublished\":\"2024-04-26T13:59:00+00:00\",\"dateModified\":\"2024-04-26T14:21:20+00:00\",\"description\":\"Cump\u0103ra\u021bi RAM Tough-Claw Baza cu clema mica cu minge \u00een Rom\u00e2nia de la Boats Expert. \u041e gam\u0103 larg\u0103 de accesorii pentru b\u0103rci cu motor cu livrare \u00een toat\u0103 Rom\u00e2nia!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boatsexpert.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg\",\"contentUrl\":\"https:\\\/\\\/boatsexpert.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg\",\"width\":555,\"height\":478,\"caption\":\"RAM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/produs\\\/ram-tough-claw-baza-cu-clema-mica-cu-minge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop Online &#8211; cel mai bun magazin pentru echipamente pentru b\u0103rci\",\"item\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/shop-ro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/\",\"name\":\"BoatsExpert\",\"description\":\"Boats, Service, Equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/#organization\",\"name\":\"BoatsExpert\",\"url\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boatsexpert.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/white-logo60.svg\",\"contentUrl\":\"https:\\\/\\\/boatsexpert.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/white-logo60.svg\",\"width\":90,\"height\":60,\"caption\":\"BoatsExpert\"},\"image\":{\"@id\":\"https:\\\/\\\/boatsexpert.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge - BoatsExpert","description":"Cump\u0103ra\u021bi RAM Tough-Claw Baza cu clema mica cu minge \u00een Rom\u00e2nia de la Boats Expert. \u041e gam\u0103 larg\u0103 de accesorii pentru b\u0103rci cu motor cu livrare \u00een toat\u0103 Rom\u00e2nia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/","og_locale":"ro_RO","og_type":"article","og_title":"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge - BoatsExpert","og_description":"Cump\u0103ra\u021bi RAM Tough-Claw Baza cu clema mica cu minge \u00een Rom\u00e2nia de la Boats Expert. \u041e gam\u0103 larg\u0103 de accesorii pentru b\u0103rci cu motor cu livrare \u00een toat\u0103 Rom\u00e2nia!","og_url":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/","og_site_name":"BoatsExpert","article_modified_time":"2024-04-26T14:21:20+00:00","og_image":[{"width":555,"height":478,"url":"https:\/\/boatsexpert.com\/wp-content\/uploads\/2024\/04\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/","url":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/","name":"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge - BoatsExpert","isPartOf":{"@id":"https:\/\/boatsexpert.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/#primaryimage"},"image":{"@id":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/#primaryimage"},"thumbnailUrl":"https:\/\/boatsexpert.com\/wp-content\/uploads\/2024\/04\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg","datePublished":"2024-04-26T13:59:00+00:00","dateModified":"2024-04-26T14:21:20+00:00","description":"Cump\u0103ra\u021bi RAM Tough-Claw Baza cu clema mica cu minge \u00een Rom\u00e2nia de la Boats Expert. \u041e gam\u0103 larg\u0103 de accesorii pentru b\u0103rci cu motor cu livrare \u00een toat\u0103 Rom\u00e2nia!","breadcrumb":{"@id":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/#primaryimage","url":"https:\/\/boatsexpert.com\/wp-content\/uploads\/2024\/04\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg","contentUrl":"https:\/\/boatsexpert.com\/wp-content\/uploads\/2024\/04\/eng_pl_RAM-R-Tough-Claw-TM-Small-Clamp-Base-with-Ball-13081_1.jpg","width":555,"height":478,"caption":"RAM"},{"@type":"BreadcrumbList","@id":"https:\/\/boatsexpert.com\/ro\/produs\/ram-tough-claw-baza-cu-clema-mica-cu-minge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boatsexpert.com\/ro\/"},{"@type":"ListItem","position":2,"name":"Shop Online &#8211; cel mai bun magazin pentru echipamente pentru b\u0103rci","item":"https:\/\/boatsexpert.com\/ro\/shop-ro\/"},{"@type":"ListItem","position":3,"name":"RAM\u00ae Tough-Claw\u2122 Baza cu clema mica cu minge"}]},{"@type":"WebSite","@id":"https:\/\/boatsexpert.com\/ro\/#website","url":"https:\/\/boatsexpert.com\/ro\/","name":"BoatsExpert","description":"Boats, Service, Equipment","publisher":{"@id":"https:\/\/boatsexpert.com\/ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boatsexpert.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/boatsexpert.com\/ro\/#organization","name":"BoatsExpert","url":"https:\/\/boatsexpert.com\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/boatsexpert.com\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/boatsexpert.com\/wp-content\/uploads\/2023\/05\/white-logo60.svg","contentUrl":"https:\/\/boatsexpert.com\/wp-content\/uploads\/2023\/05\/white-logo60.svg","width":90,"height":60,"caption":"BoatsExpert"},"image":{"@id":"https:\/\/boatsexpert.com\/ro\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/product\/32877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/comments?post=32877"}],"version-history":[{"count":0,"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/product\/32877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/media\/32879"}],"wp:attachment":[{"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/media?parent=32877"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/product_brand?post=32877"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/product_cat?post=32877"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/boatsexpert.com\/ro\/wp-json\/wp\/v2\/product_tag?post=32877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}